{"id":7173,"date":"2013-12-20T17:42:27","date_gmt":"2013-12-20T17:42:27","guid":{"rendered":"http:\/\/library.missouri.edu\/newsnotes\/?p=7173"},"modified":"2013-12-20T17:42:27","modified_gmt":"2013-12-20T17:42:27","slug":"goodbye-to-derek-wintemberg","status":"publish","type":"post","link":"https:\/\/library.missouri.edu\/newsnotes\/2013\/12\/20\/goodbye-to-derek-wintemberg\/","title":{"rendered":"Goodbye to Derek Wintemberg"},"content":{"rendered":"<p>\n\tDerek has accepted another position. His last day will be December 27.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derek has accepted another position. His last day will be December 27.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[27],"tags":[],"class_list":["post-7173","post","type-post","status-publish","format-standard","hentry","category-human-resources"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 09:22:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/7173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/comments?post=7173"}],"version-history":[{"count":1,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/7173\/revisions"}],"predecessor-version":[{"id":7174,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/7173\/revisions\/7174"}],"wp:attachment":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/media?parent=7173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/categories?post=7173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/tags?post=7173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}