{"id":3298,"date":"2011-04-01T09:32:18","date_gmt":"2011-04-01T15:32:18","guid":{"rendered":"http:\/\/mulibraries.missouri.edu\/newsnotes\/?p=3298"},"modified":"2011-04-01T09:32:18","modified_gmt":"2011-04-01T15:32:18","slug":"current-muse-post-web-tip-3","status":"publish","type":"post","link":"https:\/\/library.missouri.edu\/newsnotes\/2011\/04\/01\/current-muse-post-web-tip-3\/","title":{"rendered":"Current MUSE Post, Web Tip"},"content":{"rendered":"<p>Web tip of the week, March 28, 2011: Free Kids meals:\u00a0 <a href=\"..\/..\/muse\/index.php\/2011\/03\/31\/web-tip-of-the-week-march-28-2011-free-kids-meals\/\">http:\/\/mulibraries.missouri.edu\/muse\/index.php\/2011\/03\/31\/web-tip-of-the-week-march-28-2011-free-kids-meals\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Web tip of the week, March 28, 2011: Free Kids meals:\u00a0 http:\/\/mulibraries.missouri.edu\/muse\/index.php\/2011\/03\/31\/web-tip-of-the-week-march-28-2011-free-kids-meals\/ &nbsp;<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[36],"tags":[],"class_list":["post-3298","post","type-post","status-publish","format-standard","hentry","category-mulsa"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 12:13:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/3298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/comments?post=3298"}],"version-history":[{"count":0,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/3298\/revisions"}],"wp:attachment":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/media?parent=3298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/categories?post=3298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/tags?post=3298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}