{"id":172,"date":"2008-05-23T08:32:45","date_gmt":"2008-05-23T14:32:45","guid":{"rendered":"http:\/\/mulibraries.missouri.edu\/newsnotes\/?p=172"},"modified":"2008-05-23T08:32:45","modified_gmt":"2008-05-23T14:32:45","slug":"new-posts-may-19-23","status":"publish","type":"post","link":"https:\/\/library.missouri.edu\/newsnotes\/2008\/05\/23\/new-posts-may-19-23\/","title":{"rendered":"New Posts, May 19-23"},"content":{"rendered":"<ol>\n<li><a href=\"http:\/\/mulibraries.missouri.edu\/newsnotes\/?p=171\">Chancellor&#8217;s Walk Rescheduled<\/a><\/li>\n<li><a href=\"http:\/\/mulibraries.missouri.edu\/newsnotes\/?p=170\">Goodbye to Cathy Stubbs<\/a><\/li>\n<li><a href=\"http:\/\/mulibraries.missouri.edu\/newsnotes\/?p=169\">Job Vacancies<\/a><\/li>\n<li><a href=\"http:\/\/mulibraries.missouri.edu\/newsnotes\/?p=168\">Libraries Appointed Committees&#8211;Reminder <\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Chancellor&#8217;s Walk Rescheduled Goodbye to Cathy Stubbs Job Vacancies Libraries Appointed Committees&#8211;Reminder<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[37],"tags":[],"class_list":["post-172","post","type-post","status-publish","format-standard","hentry","category-new-posts-by-week"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 07:26:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":0,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"wp:attachment":[{"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/library.missouri.edu\/newsnotes\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}